{"id":1815,"date":"2010-04-02T21:57:30","date_gmt":"2010-04-02T20:57:30","guid":{"rendered":"http:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/"},"modified":"2010-04-02T21:57:30","modified_gmt":"2010-04-02T20:57:30","slug":"mit-dem-mac-auf-ntfs-festplatten-schreiben","status":"publish","type":"post","link":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/","title":{"rendered":"Mit dem Mac auf NTFS-Festplatten schreiben"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"border-bottom: 0px; border-left: 0px; display: inline; border-top: 0px; border-right: 0px\" title=\"image\" border=\"0\" alt=\"image\" src=\"http:\/\/www.workshop.ch\/openmind\/wp-content\/uploads\/2010\/04\/image1.png\" width=\"400\" height=\"115\" \/> <\/p>\n<p>Bekanntlich nutzt Windows das Dateisystem NTFS, wogegen Mac OS mit HFS+ arbeitet. Die Unterst\u00fctzung des jeweils anderen Dateisystems ist bei beiden Betriebssystemen nur eingeschr\u00e4nkt vorhanden. So kann ein Mac zwar von einer NTFS-Festplatte lesen, aber nicht darauf schreiben.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"border-bottom: 0px; border-left: 0px; display: inline; border-top: 0px; border-right: 0px\" title=\"image\" border=\"0\" alt=\"image\" src=\"http:\/\/www.workshop.ch\/openmind\/wp-content\/uploads\/2010\/04\/image2.png\" width=\"400\" height=\"59\" \/> <\/p>\n<p>Abhilfe schafft <a href=\"http:\/\/code.google.com\/p\/macfuse\/\">MacFUSE<\/a> in Kombination mit <a href=\"http:\/\/macntfs-3g.blogspot.com\/2010\/01\/ntfs-3g-for-mac-os-x-2010116.html\">NTFS-3G for Mac OS X<\/a>: Die Installation dieser beiden Software-Pakete (alle mit Open-Source-Lizenz) erm\u00f6glicht es, dass man \u00fcber den Finder auch NTFS-Medien ganz normal beschreiben kann. Dabei muss man nicht zwingend verstehen, was diese Software-Pakete im Detail tun: Es reicht, dass man die beiden DMG-Dateien herunterl\u00e4dt, mountet und den darin enthaltenen Installer startet. Nach einem Neustart klappt dann der Schreibzugriff auf NTFS-Festplatten automatisch, ohne dass man etwas von der eben installierten Software merken w\u00fcrde. Verschiedenen Quellen zufolge scheint der Datendurchsatz zwar nicht berauschend zu sein. Ich pers\u00f6nlich bin aber bereits hoch zufrieden, dass mein Mac nun mit Windows-Festplatten umgehen kann; und obwohl ich Dateien in GByte-Dimensionen geschrieben habe, ist mir der Zugriff nicht speziell langsam vorgekommen.<\/p>\n<p>Wenn man sieht, wie elegant MacFUSE und NTFS-3G funktionieren, dann stellt sich eigentlich nur eine Frage: Warum enth\u00e4lt uns Apple diese ausgesprochen n\u00fctzliche Funktionalit\u00e4t vor?<\/p>\n<p><span hidden class=\"__iawmlf-post-loop-links\" data-iawmlf-links=\"[{&quot;id&quot;:564,&quot;href&quot;:&quot;http:\\\/\\\/code.google.com\\\/p\\\/macfuse&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20170307012057\\\/http:\\\/\\\/code.google.com\\\/p\\\/macfuse\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2025-12-04 00:34:04&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-01-22 05:02:26&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-01-31 06:38:35&quot;,&quot;http_code&quot;:500},{&quot;date&quot;:&quot;2026-02-12 08:24:43&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-16 07:30:00&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-20 03:29:13&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-20 10:00:20&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-24 21:59:37&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-28 10:03:48&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-08 04:55:42&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-12 12:44:56&quot;,&quot;http_code&quot;:500},{&quot;date&quot;:&quot;2026-04-16 02:22:06&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-21 19:37:14&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-26 10:20:13&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-30 02:44:03&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-05-04 21:17:00&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-05-12 19:45:22&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-12 19:45:22&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:565,&quot;href&quot;:&quot;http:\\\/\\\/macntfs-3g.blogspot.com\\\/2010\\\/01\\\/ntfs-3g-for-mac-os-x-2010116.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251204005459\\\/https:\\\/\\\/macntfs-3g.blogspot.com\\\/2010\\\/01\\\/ntfs-3g-for-mac-os-x-2010116.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-01-22 05:02:24&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-01-31 06:38:38&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 08:24:42&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-16 07:30:00&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-20 03:29:13&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-20 10:00:20&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-24 21:59:41&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-28 10:03:48&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-06 21:38:05&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-12 12:44:57&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-16 02:22:05&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-21 19:37:13&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-26 10:20:13&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-30 02:44:03&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-04 21:16:59&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-12 19:45:21&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-12 19:45:21&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;}]\"><\/span><\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Bekanntlich nutzt Windows das Dateisystem NTFS, wogegen Mac OS mit HFS+ arbeitet. Die Unterst\u00fctzung des jeweils anderen Dateisystems ist bei beiden Betriebssystemen nur eingeschr\u00e4nkt vorhanden. So kann ein Mac zwar von einer NTFS-Festplatte lesen, aber nicht darauf schreiben. Abhilfe schafft MacFUSE in Kombination mit NTFS-3G for Mac OS X: Die Installation dieser beiden Software-Pakete (alle &#8230; <a title=\"Mit dem Mac auf NTFS-Festplatten schreiben\" class=\"read-more\" href=\"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/\" aria-label=\"Read more about Mit dem Mac auf NTFS-Festplatten schreiben\">Read more<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"generate_page_header":"","footnotes":""},"categories":[15],"tags":[1132,1641,1133,1642],"class_list":["post-1815","post","type-post","status-publish","format-standard","hentry","category-mac-os-x","tag-hfs","tag-macfuse","tag-ntfs","tag-ntfs-3g"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mit dem Mac auf NTFS-Festplatten schreiben - Open Mind<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mit dem Mac auf NTFS-Festplatten schreiben - Open Mind\" \/>\n<meta property=\"og:description\" content=\"Bekanntlich nutzt Windows das Dateisystem NTFS, wogegen Mac OS mit HFS+ arbeitet. Die Unterst\u00fctzung des jeweils anderen Dateisystems ist bei beiden Betriebssystemen nur eingeschr\u00e4nkt vorhanden. So kann ein Mac zwar von einer NTFS-Festplatte lesen, aber nicht darauf schreiben. Abhilfe schafft MacFUSE in Kombination mit NTFS-3G for Mac OS X: Die Installation dieser beiden Software-Pakete (alle ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/\" \/>\n<meta property=\"og:site_name\" content=\"Open Mind\" \/>\n<meta property=\"article:published_time\" content=\"2010-04-02T20:57:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.workshop.ch\/openmind\/wp-content\/uploads\/2010\/04\/image1.png\" \/>\n<meta name=\"author\" content=\"The Open Source Guy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"The Open Source Guy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/\"},\"author\":{\"name\":\"The Open Source Guy\",\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/#\\\/schema\\\/person\\\/74ece7dcefab45da1c0cc78b2e48d793\"},\"headline\":\"Mit dem Mac auf NTFS-Festplatten schreiben\",\"datePublished\":\"2010-04-02T20:57:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/\"},\"wordCount\":202,\"commentCount\":4,\"image\":{\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.workshop.ch\\\/openmind\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/image1.png\",\"keywords\":[\"HFS\",\"MacFUSE\",\"NTFS\",\"NTFS-3G\"],\"articleSection\":[\"Mac OS X\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/\",\"url\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/\",\"name\":\"Mit dem Mac auf NTFS-Festplatten schreiben - Open Mind\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.workshop.ch\\\/openmind\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/image1.png\",\"datePublished\":\"2010-04-02T20:57:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/#\\\/schema\\\/person\\\/74ece7dcefab45da1c0cc78b2e48d793\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.workshop.ch\\\/openmind\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/image1.png\",\"contentUrl\":\"http:\\\/\\\/www.workshop.ch\\\/openmind\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/image1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/2010\\\/04\\\/02\\\/mit-dem-mac-auf-ntfs-festplatten-schreiben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mit dem Mac auf NTFS-Festplatten schreiben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/#website\",\"url\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/\",\"name\":\"Open Mind\",\"description\":\"Open Source &amp; Open Content\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/#\\\/schema\\\/person\\\/74ece7dcefab45da1c0cc78b2e48d793\",\"name\":\"The Open Source Guy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/wp-content\\\/plugins\\\/avatar-privacy\\\/public\\\/images\\\/mystery.svg\",\"url\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/wp-content\\\/plugins\\\/avatar-privacy\\\/public\\\/images\\\/mystery.svg\",\"contentUrl\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/wp-content\\\/plugins\\\/avatar-privacy\\\/public\\\/images\\\/mystery.svg\",\"caption\":\"The Open Source Guy\"},\"url\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mit dem Mac auf NTFS-Festplatten schreiben - Open Mind","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/","og_locale":"de_DE","og_type":"article","og_title":"Mit dem Mac auf NTFS-Festplatten schreiben - Open Mind","og_description":"Bekanntlich nutzt Windows das Dateisystem NTFS, wogegen Mac OS mit HFS+ arbeitet. Die Unterst\u00fctzung des jeweils anderen Dateisystems ist bei beiden Betriebssystemen nur eingeschr\u00e4nkt vorhanden. So kann ein Mac zwar von einer NTFS-Festplatte lesen, aber nicht darauf schreiben. Abhilfe schafft MacFUSE in Kombination mit NTFS-3G for Mac OS X: Die Installation dieser beiden Software-Pakete (alle ... Read more","og_url":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/","og_site_name":"Open Mind","article_published_time":"2010-04-02T20:57:30+00:00","og_image":[{"url":"http:\/\/www.workshop.ch\/openmind\/wp-content\/uploads\/2010\/04\/image1.png","type":"","width":"","height":""}],"author":"The Open Source Guy","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"The Open Source Guy","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/#article","isPartOf":{"@id":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/"},"author":{"name":"The Open Source Guy","@id":"https:\/\/www.workshop.ch\/openmind\/#\/schema\/person\/74ece7dcefab45da1c0cc78b2e48d793"},"headline":"Mit dem Mac auf NTFS-Festplatten schreiben","datePublished":"2010-04-02T20:57:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/"},"wordCount":202,"commentCount":4,"image":{"@id":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/#primaryimage"},"thumbnailUrl":"http:\/\/www.workshop.ch\/openmind\/wp-content\/uploads\/2010\/04\/image1.png","keywords":["HFS","MacFUSE","NTFS","NTFS-3G"],"articleSection":["Mac OS X"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/","url":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/","name":"Mit dem Mac auf NTFS-Festplatten schreiben - Open Mind","isPartOf":{"@id":"https:\/\/www.workshop.ch\/openmind\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/#primaryimage"},"image":{"@id":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/#primaryimage"},"thumbnailUrl":"http:\/\/www.workshop.ch\/openmind\/wp-content\/uploads\/2010\/04\/image1.png","datePublished":"2010-04-02T20:57:30+00:00","author":{"@id":"https:\/\/www.workshop.ch\/openmind\/#\/schema\/person\/74ece7dcefab45da1c0cc78b2e48d793"},"breadcrumb":{"@id":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/#primaryimage","url":"http:\/\/www.workshop.ch\/openmind\/wp-content\/uploads\/2010\/04\/image1.png","contentUrl":"http:\/\/www.workshop.ch\/openmind\/wp-content\/uploads\/2010\/04\/image1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.workshop.ch\/openmind\/2010\/04\/02\/mit-dem-mac-auf-ntfs-festplatten-schreiben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.workshop.ch\/openmind\/"},{"@type":"ListItem","position":2,"name":"Mit dem Mac auf NTFS-Festplatten schreiben"}]},{"@type":"WebSite","@id":"https:\/\/www.workshop.ch\/openmind\/#website","url":"https:\/\/www.workshop.ch\/openmind\/","name":"Open Mind","description":"Open Source &amp; Open Content","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.workshop.ch\/openmind\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/www.workshop.ch\/openmind\/#\/schema\/person\/74ece7dcefab45da1c0cc78b2e48d793","name":"The Open Source Guy","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.workshop.ch\/openmind\/wp-content\/plugins\/avatar-privacy\/public\/images\/mystery.svg","url":"https:\/\/www.workshop.ch\/openmind\/wp-content\/plugins\/avatar-privacy\/public\/images\/mystery.svg","contentUrl":"https:\/\/www.workshop.ch\/openmind\/wp-content\/plugins\/avatar-privacy\/public\/images\/mystery.svg","caption":"The Open Source Guy"},"url":"https:\/\/www.workshop.ch\/openmind"}]}},"_links":{"self":[{"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/posts\/1815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/comments?post=1815"}],"version-history":[{"count":0,"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/posts\/1815\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/media?parent=1815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/categories?post=1815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/tags?post=1815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}