{"id":756,"count":2,"description":"","link":"https:\/\/www.workshop.ch\/openmind\/tag\/onecore\/","name":"Onecore","slug":"onecore","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Onecore Archive - Open Mind<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.workshop.ch\/openmind\/tag\/onecore\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Onecore Archive - Open Mind\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.workshop.ch\/openmind\/tag\/onecore\/\" \/>\n<meta property=\"og:site_name\" content=\"Open Mind\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/tag\\\/onecore\\\/\",\"url\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/tag\\\/onecore\\\/\",\"name\":\"Onecore Archive - Open Mind\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/tag\\\/onecore\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/tag\\\/onecore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Onecore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/#website\",\"url\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/\",\"name\":\"Open Mind\",\"description\":\"Open Source &amp; Open Content\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.workshop.ch\\\/openmind\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Onecore Archive - Open Mind","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.workshop.ch\/openmind\/tag\/onecore\/","og_locale":"de_DE","og_type":"article","og_title":"Onecore Archive - Open Mind","og_url":"https:\/\/www.workshop.ch\/openmind\/tag\/onecore\/","og_site_name":"Open Mind","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.workshop.ch\/openmind\/tag\/onecore\/","url":"https:\/\/www.workshop.ch\/openmind\/tag\/onecore\/","name":"Onecore Archive - Open Mind","isPartOf":{"@id":"https:\/\/www.workshop.ch\/openmind\/#website"},"breadcrumb":{"@id":"https:\/\/www.workshop.ch\/openmind\/tag\/onecore\/#breadcrumb"},"inLanguage":"de-CH"},{"@type":"BreadcrumbList","@id":"https:\/\/www.workshop.ch\/openmind\/tag\/onecore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.workshop.ch\/openmind\/"},{"@type":"ListItem","position":2,"name":"Onecore"}]},{"@type":"WebSite","@id":"https:\/\/www.workshop.ch\/openmind\/#website","url":"https:\/\/www.workshop.ch\/openmind\/","name":"Open Mind","description":"Open Source &amp; Open Content","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.workshop.ch\/openmind\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"}]}},"_links":{"self":[{"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/tags\/756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.workshop.ch\/openmind\/wp-json\/wp\/v2\/posts?tags=756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}